{"id":20150,"date":"2020-04-15T22:28:04","date_gmt":"2020-04-16T02:28:04","guid":{"rendered":"https:\/\/www.nycfoodpolicy.org\/?p=20150"},"modified":"2025-12-01T05:25:20","modified_gmt":"2025-12-01T10:25:20","slug":"nyc-food-resource-guide-upper-west-side","status":"publish","type":"post","link":"https:\/\/foodmedcenter.org\/es_mx\/nyc-food-resource-guide-upper-west-side\/","title":{"rendered":"NYC Food Resource Guide: Upper West Side"},"content":{"rendered":"<iframe src=\"https:\/\/sm-frg-pages.s3.us-east-1.amazonaws.com\/upper_west_side_en.html\" width=\"100%\" height=\"600\" style=\"border:none;\"><\/iframe>","protected":false},"excerpt":{"rendered":"","protected":false},"author":67,"featured_media":29114,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[11832],"tags":[10455,11794,11815,11816,11824,11823,11800,11807,11810,11819,11825,11437,11797],"class_list":["post-20150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food-access-guides","tag-city-harvest","tag-citymeals-on-wheels","tag-getfoodnyc","tag-gods-love-we-deliver","tag-gogogourmet","tag-gogograndparent","tag-grownyc","tag-health-bucks","tag-meals-on-wheels","tag-ny-common-pantry","tag-nycdoe","tag-snap","tag-wic"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NYC Food Resource Guide: Upper West Side<\/title>\n<meta name=\"description\" content=\"The Center is creating reports for each NYC neighborhood to help connect community members in need during this challenging time.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foodmedcenter.org\/es_mx\/nyc-food-resource-guide-upper-west-side\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NYC Food Resource Guide: Upper West Side\" \/>\n<meta property=\"og:description\" content=\"The Center is creating reports for each NYC neighborhood to help connect community members in need during this challenging time.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foodmedcenter.org\/es_mx\/nyc-food-resource-guide-upper-west-side\/\" \/>\n<meta property=\"og:site_name\" content=\"Center For Food As Medicine &amp; Longevity\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/foodmedcenter\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-16T02:28:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T10:25:20+00:00\" \/>\n<meta name=\"author\" content=\"Center For Food As Medicine &amp; Longevity Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@foodmedcenter\" \/>\n<meta name=\"twitter:site\" content=\"@foodmedcenter\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Center For Food As Medicine &amp; Longevity Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/nyc-food-resource-guide-upper-west-side\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/nyc-food-resource-guide-upper-west-side\\\/\"},\"author\":{\"name\":\"Center For Food As Medicine &amp; Longevity Staff\",\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/#\\\/schema\\\/person\\\/01f9af5f61e517221fbce1cfc09eae4e\"},\"headline\":\"NYC Food Resource Guide: Upper West Side\",\"datePublished\":\"2020-04-16T02:28:04+00:00\",\"dateModified\":\"2025-12-01T10:25:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/nyc-food-resource-guide-upper-west-side\\\/\"},\"wordCount\":14,\"publisher\":{\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/nyc-food-resource-guide-upper-west-side\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"city harvest\",\"Citymeals on Wheels\",\"GetFoodNYC\",\"God's Love We Deliver\",\"GoGoGourmet\",\"gogograndparent\",\"GrowNYC\",\"Health Bucks\",\"Meals on Wheels\",\"NY Common Pantry\",\"NYCDOE\",\"SNAP\",\"WIC\"],\"articleSection\":[\"Food Access Guides\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/es_mx\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/nyc-food-resource-guide-upper-west-side\\\/\",\"url\":\"https:\\\/\\\/foodmedcenter.org\\\/nyc-food-resource-guide-upper-west-side\\\/\",\"name\":\"NYC Food Resource Guide: Upper West Side\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/nyc-food-resource-guide-upper-west-side\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/nyc-food-resource-guide-upper-west-side\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-04-16T02:28:04+00:00\",\"dateModified\":\"2025-12-01T10:25:20+00:00\",\"description\":\"The Center is creating reports for each NYC neighborhood to help connect community members in need during this challenging time.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/nyc-food-resource-guide-upper-west-side\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/foodmedcenter.org\\\/nyc-food-resource-guide-upper-west-side\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/nyc-food-resource-guide-upper-west-side\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/nyc-food-resource-guide-upper-west-side\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/foodmedcenter.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NYC Food Resource Guide: Upper West Side\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/#website\",\"url\":\"https:\\\/\\\/foodmedcenter.org\\\/\",\"name\":\"Center For Food As Medicine & Longevity\",\"description\":\"Using Food as Medicine to Live Better, Live Healthier, and Live Longer.\",\"publisher\":{\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/foodmedcenter.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/#organization\",\"name\":\"Center For Food As Medicine & Longevity\",\"url\":\"https:\\\/\\\/foodmedcenter.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/foodmedcenter.org\\\/wp-content\\\/uploads\\\/CFFAMAL_2025_logo_square-1080.jpg\",\"contentUrl\":\"https:\\\/\\\/foodmedcenter.org\\\/wp-content\\\/uploads\\\/CFFAMAL_2025_logo_square-1080.jpg\",\"width\":1080,\"height\":1080,\"caption\":\"Center For Food As Medicine & Longevity\"},\"image\":{\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/foodmedcenter\",\"https:\\\/\\\/x.com\\\/foodmedcenter\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/foodmedcenter.org\\\/#\\\/schema\\\/person\\\/01f9af5f61e517221fbce1cfc09eae4e\",\"name\":\"Center For Food As Medicine &amp; Longevity Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/135d5270b58f010b39f031e16f54e9934c95b554f2f7cdbe94ce91a3dcfb311c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/135d5270b58f010b39f031e16f54e9934c95b554f2f7cdbe94ce91a3dcfb311c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/135d5270b58f010b39f031e16f54e9934c95b554f2f7cdbe94ce91a3dcfb311c?s=96&d=mm&r=g\",\"caption\":\"Center For Food As Medicine &amp; Longevity Staff\"},\"url\":\"https:\\\/\\\/foodmedcenter.org\\\/es_mx\\\/author\\\/cfamstaff\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NYC Food Resource Guide: Upper West Side","description":"The Center is creating reports for each NYC neighborhood to help connect community members in need during this challenging time.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foodmedcenter.org\/es_mx\/nyc-food-resource-guide-upper-west-side\/","og_locale":"es_MX","og_type":"article","og_title":"NYC Food Resource Guide: Upper West Side","og_description":"The Center is creating reports for each NYC neighborhood to help connect community members in need during this challenging time.","og_url":"https:\/\/foodmedcenter.org\/es_mx\/nyc-food-resource-guide-upper-west-side\/","og_site_name":"Center For Food As Medicine &amp; Longevity","article_publisher":"https:\/\/www.facebook.com\/foodmedcenter","article_published_time":"2020-04-16T02:28:04+00:00","article_modified_time":"2025-12-01T10:25:20+00:00","author":"Center For Food As Medicine &amp; Longevity Staff","twitter_card":"summary_large_image","twitter_creator":"@foodmedcenter","twitter_site":"@foodmedcenter","twitter_misc":{"Escrito por":"Center For Food As Medicine &amp; Longevity Staff","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foodmedcenter.org\/nyc-food-resource-guide-upper-west-side\/#article","isPartOf":{"@id":"https:\/\/foodmedcenter.org\/nyc-food-resource-guide-upper-west-side\/"},"author":{"name":"Center For Food As Medicine &amp; Longevity Staff","@id":"https:\/\/foodmedcenter.org\/#\/schema\/person\/01f9af5f61e517221fbce1cfc09eae4e"},"headline":"NYC Food Resource Guide: Upper West Side","datePublished":"2020-04-16T02:28:04+00:00","dateModified":"2025-12-01T10:25:20+00:00","mainEntityOfPage":{"@id":"https:\/\/foodmedcenter.org\/nyc-food-resource-guide-upper-west-side\/"},"wordCount":14,"publisher":{"@id":"https:\/\/foodmedcenter.org\/#organization"},"image":{"@id":"https:\/\/foodmedcenter.org\/nyc-food-resource-guide-upper-west-side\/#primaryimage"},"thumbnailUrl":"","keywords":["city harvest","Citymeals on Wheels","GetFoodNYC","God's Love We Deliver","GoGoGourmet","gogograndparent","GrowNYC","Health Bucks","Meals on Wheels","NY Common Pantry","NYCDOE","SNAP","WIC"],"articleSection":["Food Access Guides"],"inLanguage":"es","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/foodmedcenter.org\/es_mx\/#organization"}},{"@type":"WebPage","@id":"https:\/\/foodmedcenter.org\/nyc-food-resource-guide-upper-west-side\/","url":"https:\/\/foodmedcenter.org\/nyc-food-resource-guide-upper-west-side\/","name":"NYC Food Resource Guide: Upper West Side","isPartOf":{"@id":"https:\/\/foodmedcenter.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foodmedcenter.org\/nyc-food-resource-guide-upper-west-side\/#primaryimage"},"image":{"@id":"https:\/\/foodmedcenter.org\/nyc-food-resource-guide-upper-west-side\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-04-16T02:28:04+00:00","dateModified":"2025-12-01T10:25:20+00:00","description":"The Center is creating reports for each NYC neighborhood to help connect community members in need during this challenging time.","breadcrumb":{"@id":"https:\/\/foodmedcenter.org\/nyc-food-resource-guide-upper-west-side\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foodmedcenter.org\/nyc-food-resource-guide-upper-west-side\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foodmedcenter.org\/nyc-food-resource-guide-upper-west-side\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/foodmedcenter.org\/nyc-food-resource-guide-upper-west-side\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/foodmedcenter.org\/"},{"@type":"ListItem","position":2,"name":"NYC Food Resource Guide: Upper West Side"}]},{"@type":"WebSite","@id":"https:\/\/foodmedcenter.org\/#website","url":"https:\/\/foodmedcenter.org\/","name":"Center For Food As Medicine & Longevity","description":"Using Food as Medicine to Live Better, Live Healthier, and Live Longer.","publisher":{"@id":"https:\/\/foodmedcenter.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foodmedcenter.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/foodmedcenter.org\/#organization","name":"Center For Food As Medicine & Longevity","url":"https:\/\/foodmedcenter.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foodmedcenter.org\/#\/schema\/logo\/image\/","url":"https:\/\/foodmedcenter.org\/wp-content\/uploads\/CFFAMAL_2025_logo_square-1080.jpg","contentUrl":"https:\/\/foodmedcenter.org\/wp-content\/uploads\/CFFAMAL_2025_logo_square-1080.jpg","width":1080,"height":1080,"caption":"Center For Food As Medicine & Longevity"},"image":{"@id":"https:\/\/foodmedcenter.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/foodmedcenter","https:\/\/x.com\/foodmedcenter"]},{"@type":"Person","@id":"https:\/\/foodmedcenter.org\/#\/schema\/person\/01f9af5f61e517221fbce1cfc09eae4e","name":"Center For Food As Medicine &amp; Longevity Staff","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/135d5270b58f010b39f031e16f54e9934c95b554f2f7cdbe94ce91a3dcfb311c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/135d5270b58f010b39f031e16f54e9934c95b554f2f7cdbe94ce91a3dcfb311c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/135d5270b58f010b39f031e16f54e9934c95b554f2f7cdbe94ce91a3dcfb311c?s=96&d=mm&r=g","caption":"Center For Food As Medicine &amp; Longevity Staff"},"url":"https:\/\/foodmedcenter.org\/es_mx\/author\/cfamstaff\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/foodmedcenter.org\/es_mx\/wp-json\/wp\/v2\/posts\/20150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foodmedcenter.org\/es_mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foodmedcenter.org\/es_mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foodmedcenter.org\/es_mx\/wp-json\/wp\/v2\/users\/67"}],"replies":[{"embeddable":true,"href":"https:\/\/foodmedcenter.org\/es_mx\/wp-json\/wp\/v2\/comments?post=20150"}],"version-history":[{"count":0,"href":"https:\/\/foodmedcenter.org\/es_mx\/wp-json\/wp\/v2\/posts\/20150\/revisions"}],"wp:attachment":[{"href":"https:\/\/foodmedcenter.org\/es_mx\/wp-json\/wp\/v2\/media?parent=20150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foodmedcenter.org\/es_mx\/wp-json\/wp\/v2\/categories?post=20150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foodmedcenter.org\/es_mx\/wp-json\/wp\/v2\/tags?post=20150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}